{"id":17190,"date":"2020-11-10T12:42:43","date_gmt":"2020-11-10T11:42:43","guid":{"rendered":"https:\/\/www.bazarbonino.com\/store\/?post_type=product&#038;p=17190"},"modified":"2022-03-03T18:46:16","modified_gmt":"2022-03-03T17:46:16","slug":"mp040-mazzo-di-carte-honeybee-special-edition-metalluxe","status":"publish","type":"product","link":"https:\/\/www.bazarbonino.com\/store\/prodotto\/mp040-mazzo-di-carte-honeybee-special-edition-metalluxe\/","title":{"rendered":"MP040 &#8211; Mazzo di Carte Honeybee Special Edition MetalLuxe"},"content":{"rendered":"<p>MP040 &#8211; Mazzo di Carte Honeybee Special Edition MetalLuxe E&#8217; un vero lavoro d&#8217;amore. Progettato da Randy Butterfield, Honeybee Special Edition utilizza la tecnologia pi\u00f9 avanzata da cima a fondo.<\/p>\n<p>Per anni, l&#8217;unico modo per dare un aspetto brillante a un mazzo era l&#8217;inchiostro metallico. Tuttavia, l&#8217;inchiostro viene assorbito dalla carta e produce solo un effetto sottile. USPCC ha recentemente sviluppato una tecnologia chiamata MetalLuxe che consente loro di applicare la lamina direttamente sulle carte senza alterare la sensazione e la maneggevolezza. La lamina MetalLuxe crea un livello di lucentezza che non ha eguali.<br \/>\nE&#8217; stata applicata la lamina dorata sopra l&#8217;inchiostro nero per far risaltare il meraviglioso motivo a nido d&#8217;ape. Deve essere visto per essere creduto.<\/p>\n<p>Delle carte cos\u00ec speciali hanno sicuramente bisogno di un astuccio che si abbini&#8230; e questa astuccio \u00e8 tutt&#8217;altro che ordinario. \u00c8 realizzato in carta nera di alta qualit\u00e0 (non inchiostro nero stampato su carta bianca), con DUE tipi di lamine. La scatola nera con l&#8217;oro scintillante e la lamina d&#8217;argento annuncia che le carte all&#8217;interno sono davvero uno spettacolo da vedere e saranno immediatamente visibili nella vostra collezione.<\/p>\n<p>Sulle facce, ci sono Beekeeper Jokers personalizzati, un Beehive asso di picche personalizzato, un profondo rosso sui semi cuori\/quadri e colori e trame personalizzati applicati alle figure. La maneggevolezza \u00e8 eccellente come tutti i mazzi Honeybee, con cartoncino casino-grade Bee e finitura ultra-smooth per resistere a una notte di esibizioni.<\/p>\n<p>Questi mazzi in edizione speciale sono veri oggetti da collezionare che non saranno mai ristampati. Prendete il vostro prima che volino via!<\/p>\n<p>&#8211; Meno di 2.000 mazzi stampati.<br \/>\n&#8211; Disegnato da Randy Butterfield.<br \/>\n&#8211; Dorsi in lamina dorata MetalLuxe.<br \/>\n&#8211; Astuccio in carta nera con inserto in lamina dorata e argentata.<br \/>\n&#8211; Stampato dalla USPCC.<br \/>\n&#8211; Cartoncino Bee e finitura Premium &#8220;Magic&#8221;.<br \/>\n&#8211; Taglio tradizionale.<br \/>\n&#8211; I dorsi, astuccio,asso di picche e Joker sono personalizzati.<br \/>\n&#8211; Schema colori personalizzato e motivo di sfondo sulle figure.<br \/>\n&#8211; 2 carte Gaff incluse &#8211; Doppio dorso dorato\/giallo e faccia bianca.<\/p>\n<p>\u2022 Le carte sono formato poker.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MP040 &#8211; Mazzo di Carte Honeybee Special Edition MetalLuxe E&#8217; un vero lavoro d&#8217;amore. Progettato da Randy Butterfield, Honeybee Special Edition utilizza la tecnologia pi\u00f9 avanzata da cima a fondo. Per anni, l&#8217;unico modo per dare un aspetto brillante a un mazzo era l&#8217;inchiostro metallico. Tuttavia, l&#8217;inchiostro viene assorbito dalla carta e produce solo un [&hellip;]<\/p>\n","protected":false},"featured_media":17191,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[2245],"product_tag":[2251,2252],"class_list":["post-17190","product","type-product","status-publish","has-post-thumbnail","product_cat-mazzi-di-carte-penguin-magic","product_tag-mazzo-di-carte-honeybee-special-edition-metalluxe","product_tag-playing-card-honeybee-special-edition-metalluxe","pa_colore-blu","pa_colore-rosso","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MP040 - Mazzo di Carte Honeybee Special Edition MetalLuxe - BazarBonino<\/title>\n<meta name=\"description\" content=\"Mazzo di Carte Honeybee Special Edition MetalLuxe E&#039; un vero lavoro d&#039;amore. Progettato da Randy Butterfield, utilizza la tecnologia pi\u00f9...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bazarbonino.com\/store\/prodotto\/mp040-mazzo-di-carte-honeybee-special-edition-metalluxe\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MP040 - Mazzo di Carte Honeybee Special Edition MetalLuxe - BazarBonino\" \/>\n<meta property=\"og:description\" content=\"Mazzo di Carte Honeybee Special Edition MetalLuxe E&#039; un vero lavoro d&#039;amore. Progettato da Randy Butterfield, utilizza la tecnologia pi\u00f9...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bazarbonino.com\/store\/prodotto\/mp040-mazzo-di-carte-honeybee-special-edition-metalluxe\/\" \/>\n<meta property=\"og:site_name\" content=\"BazarBonino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bazar.bonino\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-03T17:46:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bazarbonino.com\/store\/wp-content\/uploads\/2020\/11\/MP040-Mazzo-di-Carte-Honeybee-Special-Edition-MetalLuxe.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"740\" \/>\n\t<meta property=\"og:image:height\" content=\"416\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bazarbonino.com\\\/store\\\/prodotto\\\/mp040-mazzo-di-carte-honeybee-special-edition-metalluxe\\\/\",\"url\":\"https:\\\/\\\/www.bazarbonino.com\\\/store\\\/prodotto\\\/mp040-mazzo-di-carte-honeybee-special-edition-metalluxe\\\/\",\"name\":\"MP040 - Mazzo di Carte Honeybee Special Edition MetalLuxe - BazarBonino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bazarbonino.com\\\/store\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bazarbonino.com\\\/store\\\/prodotto\\\/mp040-mazzo-di-carte-honeybee-special-edition-metalluxe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bazarbonino.com\\\/store\\\/prodotto\\\/mp040-mazzo-di-carte-honeybee-special-edition-metalluxe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bazarbonino.com\\\/store\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/MP040-Mazzo-di-Carte-Honeybee-Special-Edition-MetalLuxe.jpg\",\"datePublished\":\"2020-11-10T11:42:43+00:00\",\"dateModified\":\"2022-03-03T17:46:16+00:00\",\"description\":\"Mazzo di Carte Honeybee Special Edition MetalLuxe E' un vero lavoro d'amore. Progettato da Randy Butterfield, utilizza la tecnologia pi\u00f9...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bazarbonino.com\\\/store\\\/prodotto\\\/mp040-mazzo-di-carte-honeybee-special-edition-metalluxe\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bazarbonino.com\\\/store\\\/prodotto\\\/mp040-mazzo-di-carte-honeybee-special-edition-metalluxe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.bazarbonino.com\\\/store\\\/prodotto\\\/mp040-mazzo-di-carte-honeybee-special-edition-metalluxe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bazarbonino.com\\\/store\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/MP040-Mazzo-di-Carte-Honeybee-Special-Edition-MetalLuxe.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bazarbonino.com\\\/store\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/MP040-Mazzo-di-Carte-Honeybee-Special-Edition-MetalLuxe.jpg\",\"width\":740,\"height\":416,\"caption\":\"MP040 - Mazzo di Carte Honeybee Special Edition MetalLuxe\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bazarbonino.com\\\/store\\\/prodotto\\\/mp040-mazzo-di-carte-honeybee-special-edition-metalluxe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bazarbonino.com\\\/store\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Catalogo\",\"item\":\"https:\\\/\\\/www.bazarbonino.com\\\/store\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MP040 &#8211; Mazzo di Carte Honeybee Special Edition MetalLuxe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bazarbonino.com\\\/store\\\/#website\",\"url\":\"https:\\\/\\\/www.bazarbonino.com\\\/store\\\/\",\"name\":\"BazarBonino\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bazarbonino.com\\\/store\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MP040 - Mazzo di Carte Honeybee Special Edition MetalLuxe - BazarBonino","description":"Mazzo di Carte Honeybee Special Edition MetalLuxe E' un vero lavoro d'amore. Progettato da Randy Butterfield, utilizza la tecnologia pi\u00f9...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bazarbonino.com\/store\/prodotto\/mp040-mazzo-di-carte-honeybee-special-edition-metalluxe\/","og_locale":"it_IT","og_type":"article","og_title":"MP040 - Mazzo di Carte Honeybee Special Edition MetalLuxe - BazarBonino","og_description":"Mazzo di Carte Honeybee Special Edition MetalLuxe E' un vero lavoro d'amore. Progettato da Randy Butterfield, utilizza la tecnologia pi\u00f9...","og_url":"https:\/\/www.bazarbonino.com\/store\/prodotto\/mp040-mazzo-di-carte-honeybee-special-edition-metalluxe\/","og_site_name":"BazarBonino","article_publisher":"https:\/\/www.facebook.com\/bazar.bonino","article_modified_time":"2022-03-03T17:46:16+00:00","og_image":[{"width":740,"height":416,"url":"https:\/\/www.bazarbonino.com\/store\/wp-content\/uploads\/2020\/11\/MP040-Mazzo-di-Carte-Honeybee-Special-Edition-MetalLuxe.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bazarbonino.com\/store\/prodotto\/mp040-mazzo-di-carte-honeybee-special-edition-metalluxe\/","url":"https:\/\/www.bazarbonino.com\/store\/prodotto\/mp040-mazzo-di-carte-honeybee-special-edition-metalluxe\/","name":"MP040 - Mazzo di Carte Honeybee Special Edition MetalLuxe - BazarBonino","isPartOf":{"@id":"https:\/\/www.bazarbonino.com\/store\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bazarbonino.com\/store\/prodotto\/mp040-mazzo-di-carte-honeybee-special-edition-metalluxe\/#primaryimage"},"image":{"@id":"https:\/\/www.bazarbonino.com\/store\/prodotto\/mp040-mazzo-di-carte-honeybee-special-edition-metalluxe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bazarbonino.com\/store\/wp-content\/uploads\/2020\/11\/MP040-Mazzo-di-Carte-Honeybee-Special-Edition-MetalLuxe.jpg","datePublished":"2020-11-10T11:42:43+00:00","dateModified":"2022-03-03T17:46:16+00:00","description":"Mazzo di Carte Honeybee Special Edition MetalLuxe E' un vero lavoro d'amore. Progettato da Randy Butterfield, utilizza la tecnologia pi\u00f9...","breadcrumb":{"@id":"https:\/\/www.bazarbonino.com\/store\/prodotto\/mp040-mazzo-di-carte-honeybee-special-edition-metalluxe\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bazarbonino.com\/store\/prodotto\/mp040-mazzo-di-carte-honeybee-special-edition-metalluxe\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.bazarbonino.com\/store\/prodotto\/mp040-mazzo-di-carte-honeybee-special-edition-metalluxe\/#primaryimage","url":"https:\/\/www.bazarbonino.com\/store\/wp-content\/uploads\/2020\/11\/MP040-Mazzo-di-Carte-Honeybee-Special-Edition-MetalLuxe.jpg","contentUrl":"https:\/\/www.bazarbonino.com\/store\/wp-content\/uploads\/2020\/11\/MP040-Mazzo-di-Carte-Honeybee-Special-Edition-MetalLuxe.jpg","width":740,"height":416,"caption":"MP040 - Mazzo di Carte Honeybee Special Edition MetalLuxe"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bazarbonino.com\/store\/prodotto\/mp040-mazzo-di-carte-honeybee-special-edition-metalluxe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bazarbonino.com\/store\/"},{"@type":"ListItem","position":2,"name":"Catalogo","item":"https:\/\/www.bazarbonino.com\/store\/shop\/"},{"@type":"ListItem","position":3,"name":"MP040 &#8211; Mazzo di Carte Honeybee Special Edition MetalLuxe"}]},{"@type":"WebSite","@id":"https:\/\/www.bazarbonino.com\/store\/#website","url":"https:\/\/www.bazarbonino.com\/store\/","name":"BazarBonino","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bazarbonino.com\/store\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.bazarbonino.com\/store\/wp-json\/wp\/v2\/product\/17190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bazarbonino.com\/store\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.bazarbonino.com\/store\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bazarbonino.com\/store\/wp-json\/wp\/v2\/comments?post=17190"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bazarbonino.com\/store\/wp-json\/wp\/v2\/media\/17191"}],"wp:attachment":[{"href":"https:\/\/www.bazarbonino.com\/store\/wp-json\/wp\/v2\/media?parent=17190"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.bazarbonino.com\/store\/wp-json\/wp\/v2\/product_brand?post=17190"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.bazarbonino.com\/store\/wp-json\/wp\/v2\/product_cat?post=17190"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.bazarbonino.com\/store\/wp-json\/wp\/v2\/product_tag?post=17190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}